{"id":819,"date":"2023-01-28T18:29:50","date_gmt":"2023-01-28T18:29:50","guid":{"rendered":"https:\/\/jesuscampos.com\/blog\/?p=819"},"modified":"2023-10-19T15:07:36","modified_gmt":"2023-10-19T15:07:36","slug":"el-solitario-de-concha-mendez","status":"publish","type":"post","link":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/","title":{"rendered":"El solitario, de Concha M\u00e9ndez"},"content":{"rendered":"<h4><em>El solitario<\/em>, de Concha M\u00e9ndez<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-676\" src=\"https:\/\/jesuscampos.com\/blog\/wp-content\/uploads\/2023\/07\/EL-SOLITARIO.jpg\" alt=\"El solitario, de Concha M\u00e9ndez\" width=\"843\" height=\"843\" srcset=\"https:\/\/jesuscampos.com\/blog\/wp-content\/uploads\/2023\/07\/EL-SOLITARIO.jpg 843w, https:\/\/jesuscampos.com\/blog\/wp-content\/uploads\/2023\/07\/EL-SOLITARIO-480x480.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 843px, 100vw\" \/><\/p>\n<p>El lunes 30, a las 19,00, se presenta la edici\u00f3n de <em>El Solitario<\/em> de Concha M\u00e9ndez. Una bell\u00edsima obra teatral escrita en el exilio que nunca se hab\u00eda publicado completa en Espa\u00f1a. La cita es en la Residencia de Estudiantes, donde se conserva su legado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El solitario, de Concha M\u00e9ndez El lunes 30, a las 19,00, se presenta la edici\u00f3n de El Solitario de Concha M\u00e9ndez. Una bell\u00edsima obra teatral escrita en el exilio que nunca se hab\u00eda publicado completa en Espa\u00f1a. La cita es en la Residencia de Estudiantes, donde se conserva su legado.<\/p>\n","protected":false},"author":3,"featured_media":676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[37,38,40,41,42,43,45,47,48,90,91],"class_list":["post-819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-del-entorno","tag-el-solitario","tag-concha-mendez","tag-teatro-poetico","tag-teatro-modernista","tag-berta-munoz","tag-diego-santos","tag-teatro-en-verso","tag-teatro-del-exilio","tag-exilio-republicano-de-1939","tag-editorial-catedra","tag-letras-hispanicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El solitario, de Concha M\u00e9ndez - BLOG DE NUEVOS CUELGUES<\/title>\n<meta name=\"description\" content=\"Obra teatral El Solitario. Misterio teatral en tres actos. Obra escrita por Concha M\u00e9ndez durante su exilio en Bruselas, Cuba y M\u00e9xico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El solitario, de Concha M\u00e9ndez - BLOG DE NUEVOS CUELGUES\" \/>\n<meta property=\"og:description\" content=\"Obra teatral El Solitario. Misterio teatral en tres actos. Obra escrita por Concha M\u00e9ndez durante su exilio en Bruselas, Cuba y M\u00e9xico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG DE NUEVOS CUELGUES\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-28T18:29:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-19T15:07:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jesuscampos.com\/blog\/wp-content\/uploads\/2023\/07\/EL-SOLITARIO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"843\" \/>\n\t<meta property=\"og:image:height\" content=\"843\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jes\u00fas Campos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jes\u00fas Campos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/\"},\"author\":{\"name\":\"Jes\u00fas Campos\",\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/#\\\/schema\\\/person\\\/3cc8fc4f9758d022fed2d6cd6fa162b3\"},\"headline\":\"El solitario, de Concha M\u00e9ndez\",\"datePublished\":\"2023-01-28T18:29:50+00:00\",\"dateModified\":\"2023-10-19T15:07:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/\"},\"wordCount\":60,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/EL-SOLITARIO.jpg\",\"keywords\":[\"el solitario\",\"concha m\u00e9ndez\",\"teatro po\u00e9tico\",\"teatro modernista\",\"berta mu\u00f1oz\",\"diego santos\",\"teatro en verso\",\"teatro del exilio\",\"exilio republicano de 1939\",\"Editorial C\u00e1tedra\",\"Letras Hisp\u00e1nicas\"],\"articleSection\":[\"Del entorno\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/\",\"url\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/\",\"name\":\"El solitario, de Concha M\u00e9ndez - BLOG DE NUEVOS CUELGUES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/EL-SOLITARIO.jpg\",\"datePublished\":\"2023-01-28T18:29:50+00:00\",\"dateModified\":\"2023-10-19T15:07:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/#\\\/schema\\\/person\\\/3cc8fc4f9758d022fed2d6cd6fa162b3\"},\"description\":\"Obra teatral El Solitario. Misterio teatral en tres actos. Obra escrita por Concha M\u00e9ndez durante su exilio en Bruselas, Cuba y M\u00e9xico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/EL-SOLITARIO.jpg\",\"contentUrl\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/EL-SOLITARIO.jpg\",\"width\":843,\"height\":843,\"caption\":\"El solitario, de Concha M\u00e9ndez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/movidas-de-actualidad\\\/del-entorno\\\/el-solitario-de-concha-mendez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El solitario, de Concha M\u00e9ndez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/\",\"name\":\"BLOG DE NUEVOS CUELGUES\",\"description\":\"Blog de Jes\u00fas Campos Garc\u00eda. Novelista, autor teatral, director y escen\u00f3grafo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/#\\\/schema\\\/person\\\/3cc8fc4f9758d022fed2d6cd6fa162b3\",\"name\":\"Jes\u00fas Campos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/335943b5c9089b9f0b270f00aa7dfa70455a2d6a5896603d1791031bce6da3d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/335943b5c9089b9f0b270f00aa7dfa70455a2d6a5896603d1791031bce6da3d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/335943b5c9089b9f0b270f00aa7dfa70455a2d6a5896603d1791031bce6da3d9?s=96&d=mm&r=g\",\"caption\":\"Jes\u00fas Campos\"},\"url\":\"https:\\\/\\\/jesuscampos.com\\\/blog\\\/author\\\/jesus_campos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El solitario, de Concha M\u00e9ndez - BLOG DE NUEVOS CUELGUES","description":"Obra teatral El Solitario. Misterio teatral en tres actos. Obra escrita por Concha M\u00e9ndez durante su exilio en Bruselas, Cuba y M\u00e9xico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/","og_locale":"es_ES","og_type":"article","og_title":"El solitario, de Concha M\u00e9ndez - BLOG DE NUEVOS CUELGUES","og_description":"Obra teatral El Solitario. Misterio teatral en tres actos. Obra escrita por Concha M\u00e9ndez durante su exilio en Bruselas, Cuba y M\u00e9xico.","og_url":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/","og_site_name":"BLOG DE NUEVOS CUELGUES","article_published_time":"2023-01-28T18:29:50+00:00","article_modified_time":"2023-10-19T15:07:36+00:00","og_image":[{"width":843,"height":843,"url":"https:\/\/jesuscampos.com\/blog\/wp-content\/uploads\/2023\/07\/EL-SOLITARIO.jpg","type":"image\/jpeg"}],"author":"Jes\u00fas Campos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jes\u00fas Campos","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/#article","isPartOf":{"@id":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/"},"author":{"name":"Jes\u00fas Campos","@id":"https:\/\/jesuscampos.com\/blog\/#\/schema\/person\/3cc8fc4f9758d022fed2d6cd6fa162b3"},"headline":"El solitario, de Concha M\u00e9ndez","datePublished":"2023-01-28T18:29:50+00:00","dateModified":"2023-10-19T15:07:36+00:00","mainEntityOfPage":{"@id":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/"},"wordCount":60,"commentCount":0,"image":{"@id":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/#primaryimage"},"thumbnailUrl":"https:\/\/jesuscampos.com\/blog\/wp-content\/uploads\/2023\/07\/EL-SOLITARIO.jpg","keywords":["el solitario","concha m\u00e9ndez","teatro po\u00e9tico","teatro modernista","berta mu\u00f1oz","diego santos","teatro en verso","teatro del exilio","exilio republicano de 1939","Editorial C\u00e1tedra","Letras Hisp\u00e1nicas"],"articleSection":["Del entorno"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/","url":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/","name":"El solitario, de Concha M\u00e9ndez - BLOG DE NUEVOS CUELGUES","isPartOf":{"@id":"https:\/\/jesuscampos.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/#primaryimage"},"image":{"@id":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/#primaryimage"},"thumbnailUrl":"https:\/\/jesuscampos.com\/blog\/wp-content\/uploads\/2023\/07\/EL-SOLITARIO.jpg","datePublished":"2023-01-28T18:29:50+00:00","dateModified":"2023-10-19T15:07:36+00:00","author":{"@id":"https:\/\/jesuscampos.com\/blog\/#\/schema\/person\/3cc8fc4f9758d022fed2d6cd6fa162b3"},"description":"Obra teatral El Solitario. Misterio teatral en tres actos. Obra escrita por Concha M\u00e9ndez durante su exilio en Bruselas, Cuba y M\u00e9xico.","breadcrumb":{"@id":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/#primaryimage","url":"https:\/\/jesuscampos.com\/blog\/wp-content\/uploads\/2023\/07\/EL-SOLITARIO.jpg","contentUrl":"https:\/\/jesuscampos.com\/blog\/wp-content\/uploads\/2023\/07\/EL-SOLITARIO.jpg","width":843,"height":843,"caption":"El solitario, de Concha M\u00e9ndez"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuscampos.com\/blog\/movidas-de-actualidad\/del-entorno\/el-solitario-de-concha-mendez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jesuscampos.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El solitario, de Concha M\u00e9ndez"}]},{"@type":"WebSite","@id":"https:\/\/jesuscampos.com\/blog\/#website","url":"https:\/\/jesuscampos.com\/blog\/","name":"BLOG DE NUEVOS CUELGUES","description":"Blog de Jes\u00fas Campos Garc\u00eda. Novelista, autor teatral, director y escen\u00f3grafo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuscampos.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/jesuscampos.com\/blog\/#\/schema\/person\/3cc8fc4f9758d022fed2d6cd6fa162b3","name":"Jes\u00fas Campos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/335943b5c9089b9f0b270f00aa7dfa70455a2d6a5896603d1791031bce6da3d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/335943b5c9089b9f0b270f00aa7dfa70455a2d6a5896603d1791031bce6da3d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/335943b5c9089b9f0b270f00aa7dfa70455a2d6a5896603d1791031bce6da3d9?s=96&d=mm&r=g","caption":"Jes\u00fas Campos"},"url":"https:\/\/jesuscampos.com\/blog\/author\/jesus_campos\/"}]}},"jetpack_featured_media_url":"https:\/\/jesuscampos.com\/blog\/wp-content\/uploads\/2023\/07\/EL-SOLITARIO.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/posts\/819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/comments?post=819"}],"version-history":[{"count":9,"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/posts\/819\/revisions"}],"predecessor-version":[{"id":1764,"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/posts\/819\/revisions\/1764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/media\/676"}],"wp:attachment":[{"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/media?parent=819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/categories?post=819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jesuscampos.com\/blog\/wp-json\/wp\/v2\/tags?post=819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}